{"id":5124,"date":"2020-04-15T10:59:41","date_gmt":"2020-04-15T09:59:41","guid":{"rendered":"https:\/\/cuevalarocio.es\/?p=5124"},"modified":"2026-06-23T18:04:50","modified_gmt":"2026-06-23T17:04:50","slug":"la-zambra-del-sacromonte","status":"publish","type":"post","link":"https:\/\/cuevalarocio.es\/fr\/la-zambra-del-sacromonte\/","title":{"rendered":"La Zambra del Sacromonte"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.4.3&Prime;][et_pb_row _builder_version=\u00a0\u00bb4.4.3&Prime; custom_padding=\u00a0\u00bb||32px|||\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.4.3&Prime;][et_pb_image src=\u00a0\u00bbhttps:\/\/cuevalarocio.es\/wp-content\/uploads\/2013\/09\/zambra_gitana-2.jpg\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.3&Prime;][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.4.3&Prime;]<\/p>\n<h2><strong>La zambra gitana del sacromonte<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">La zambra es un baile t\u00edpico de los gitanos del Sacromonte. En referencia a este baile no existe una unanimidad sobre su origen, debido a la cantidad de culturas que han pasado por Granada, la idea m\u00e1s aceptada se remonta a la poblaci\u00f3n morisca que junto a los gitanos, arraig\u00f3 durante el transcurso del tiempo. La zambra tiene una presencia muy clara en las bodas gitanas del Sacromonte granadino y en su configuraci\u00f3n se divide en tres bailes principales, que son la Albore\u00e1, la Cachucha y la Mosca. Cada uno de estos bailes representa los momentos ceremoniales de la boda. Antiguamente estos bailes se bailaban con los pies descalzos, con las camisas anudadas a la cintura y faldas de vuelo.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.4.3&Prime; custom_padding=\u00a0\u00bb32px||32px|||\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.4.3&Prime;][et_pb_text _builder_version=\u00a0\u00bb4.4.3&Prime;]<\/p>\n<h2><strong>La boda gitana del Sacromonte granadino<\/strong><\/h2>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/cuevalarocio.es\/wp-content\/uploads\/2013\/11\/espectaculo-slider02.jpg\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.3&Prime;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.4.3&Prime; custom_padding=\u00a0\u00bb32px||32px|||\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.4.3&Prime;][et_pb_text _builder_version=\u00a0\u00bb4.4.3&Prime;]<\/p>\n<h3><strong>La Albore\u00e1<\/strong><\/h3>\n<p>La denominaci\u00f3n procede de alborada, por el momento en que se desarrolla la ceremonia, al alba. Es la<strong>\u00a0<\/strong>prueba de la pureza de la novia. Suelen ser bailes cantados donde predomina lo\u00a0coreogr\u00e1fico. Lleva un<strong>\u00a0ritmo de sole\u00e1 por buler\u00edas<\/strong> y se acompa\u00f1a preferentemente con guitarra y palmas.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.4.3&Prime;][et_pb_text _builder_version=\u00a0\u00bb4.4.3&Prime;]<\/p>\n<h3><strong>La cachuch\u00e1<\/strong><\/h3>\n<p>Por lo general <strong>bailado por dos mujeres.<\/strong><strong>\u00a0<\/strong>Uno de sus pasos espec\u00edficos obliga a arrodillarse a una de ellas, representando el momento en que el novio solicita perd\u00f3n a los padres de la novia por raptarla.\u00a0Bailan\u00a0todas las parejas formando rueda a los novios.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.4.3&Prime; custom_padding=\u00a0\u00bb32px||33px|||\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.4.3&Prime;][et_pb_image src=\u00a0\u00bbhttps:\/\/cuevalarocio.es\/wp-content\/uploads\/2013\/11\/boda_gitana-1.jpg\u00a0\u00bb _builder_version=\u00a0\u00bb4.4.3&Prime;][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.4.3&Prime;][et_pb_text _builder_version=\u00a0\u00bb4.4.3&Prime;]<\/p>\n<h3><strong>La Mosca<\/strong><\/h3>\n<p>Este baile consta de dos partes. En la primera se colocan frente a frente algunas parejas de mujeres, normalmente cuatro, y dan algunos pasos de los que el m\u00e1s caracter\u00edstico consiste en levantar con fuerza una pierna para girar despu\u00e9s en sentido contrario. En la segunda forman todas una gran rueda que gira sin cesar mientras las bailaoras se jalean repitiendo como estribillo \u201c\u00a1mosca!\u201d, al tiempo que levantan cada cuatro pasos la pierna derecha y se golpean el delantal con la misma mano. Pone punto y final al ceremonial de las nupcias.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.4.3&Prime; custom_padding=\u00a0\u00bb32px||32px|||\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.4.3&Prime;][et_pb_text _builder_version=\u00a0\u00bb4.4.3&Prime; hover_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h2><strong>La tradici\u00f3n en las Cuevas del Sacromonte<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Durante el siglo XVI este tipo de baile estuvo prohibido por la inquisici\u00f3n al considerarse un baile indecente, aun as\u00ed se sigui\u00f3 realiz\u00e1ndose en la clandestinidad, en la privacidad de las cuevas del Sacromonte, manteniendo viva su tradici\u00f3n. Siglos m\u00e1s tarde, durante el siglo XIX, con la llegada de los viajeros rom\u00e1nticos que visitaron Granada y divulgaron la imagen t\u00edpica de los gitanos bailando flamenco en las cuevas del Sacromonte, las cuevas, las costumbres, y tradiciones, junto a la zambra gitana capt\u00f3 el inter\u00e9s de estos turistas divulgando su imagen por todo el mundo. Los gitanos realizaban espect\u00e1culos para disfrute de estos viajeros que ven\u00edan buscando la esencia de los lugares que visitaban.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El flamenco a principios del siglo XX tuvo una presencia muy notable en algunos miembros de la generaci\u00f3n del 27 como Federico Garc\u00eda Lorca o Manuel de Falla, que organizaron concursos de flamenco, acontecimiento que se inici\u00f3 con fuerza sobre el t\u00e9rmino \u201ccante jondo\u201d, esto ayud\u00f3 a popularizar\u00a0 y poner en primer plano de la escena el flamenco y la cultura gitana que hay entorno al flamenco.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Actualmente en febrero de 2019 el ayuntamiento de Granada propuso una iniciativa para que la \u201c<strong>Zambra del Sacromonte<\/strong>\u201d fuera considerada patrimonio de la humanidad, iniciativa apoyado por todas las zambras que actualmente hay en la ciudad de Granada.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>La Zambra del Sacromonte en la Cueva la Roc\u00edo<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">La Zambra durante mucho tiempo fue sin\u00f3nimo de fiesta, jolgorio, celebraci\u00f3n, un tipo de espect\u00e1culo muy caracter\u00edstico que se celebra con los asistentes sentados en sillas de anea dispuestas en hileras a los lados de la cueva y las bailaoras y bailaores realizan el espect\u00e1culo a tan solo unos cent\u00edmetros de los asistentes, haciendo part\u00edcipe en primer plano a todos los que participan en la zambra. Es muy f\u00e1cil verse envuelto en la magia que se produce durante la zambra, es un espect\u00e1culo intenso y a diferencia del tablao flamenco, en la zambra el escenario est\u00e1 entre los espectadores.<br \/><\/span><b>La zambra gitana, es uno de los bailes m\u00e1s antiguos y puros del flamenco.<\/b><\/p>\n<p>En el<strong><a href=\"https:\/\/cuevalarocio.es\/espectaculo-flamenco-en-granada\/\"> espect\u00e1culo flamenco de la Cueva la Roc\u00edo<\/a>, <\/strong>se hace una<strong> representaci\u00f3n de una boda gitana<\/strong> a trav\u00e9s de nuestros cantes y bailes como la cachucha, rueda de tangos de grana y buler\u00edas para festejar la boda, presentaci\u00f3n de los novios, arb\u00f3rea y fandango del Albayzin. Despu\u00e9s una segunda parte donde presenta un espect\u00e1culo flamenco mucho \u00a0m\u00e1s est\u00e9tico y de palos m\u00e1s fuertes del flamenco como Martinete Siguidiyas, Alegr\u00edas, Solea y nuestro GRANADA de Agust\u00edn Lara hecho en flamenco. El Espect\u00e1culo finaliza con la Rumba y es el momento en el que nuestros clientes son invitados a salir a bailar con los artistas.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La zambra gitana del sacromonte &nbsp; La zambra es un baile t\u00edpico de los gitanos del Sacromonte. En referencia a este baile no existe una unanimidad sobre su origen, debido a la cantidad de culturas que han pasado por Granada, la idea m\u00e1s aceptada se remonta a la poblaci\u00f3n morisca que junto a los gitanos, [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-5124","post","type-post","status-publish","format-standard","hentry","category-espectaculos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Zambra del Sacromonte y la boda gitana<\/title>\n<meta name=\"description\" content=\"La zambra es un baile t\u00edpico de los gitanos del Sacromonte y tiene una presencia muy clara en las bodas gitanas del Sacromonte granadino.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cuevalarocio.es\/fr\/la-zambra-del-sacromonte\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Zambra del Sacromonte y la boda gitana\" \/>\n<meta property=\"og:description\" content=\"La zambra es un baile t\u00edpico de los gitanos del Sacromonte y tiene una presencia muy clara en las bodas gitanas del Sacromonte granadino.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cuevalarocio.es\/fr\/la-zambra-del-sacromonte\/\" \/>\n<meta property=\"og:site_name\" content=\"Cueva de La Roc\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cuevalarocio\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-15T09:59:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-23T17:04:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cuevalarocio.es\/wp-content\/uploads\/2013\/09\/flamenco_1080x450.jpg\" \/>\n<meta name=\"author\" content=\"Adriana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cuevalarocio\" \/>\n<meta name=\"twitter:site\" content=\"@cuevalarocio\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adriana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cuevalarocio.es\\\/fr\\\/la-zambra-del-sacromonte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cuevalarocio.es\\\/fr\\\/la-zambra-del-sacromonte\\\/\"},\"author\":{\"name\":\"Adriana\",\"@id\":\"https:\\\/\\\/cuevalarocio.es\\\/fr\\\/#\\\/schema\\\/person\\\/f3c08095e0eef4f5a76f7cdcf76ee226\"},\"headline\":\"La Zambra del Sacromonte\",\"datePublished\":\"2020-04-15T09:59:41+00:00\",\"dateModified\":\"2026-06-23T17:04:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cuevalarocio.es\\\/fr\\\/la-zambra-del-sacromonte\\\/\"},\"wordCount\":1066,\"articleSection\":[\"espect\u00e1culos\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cuevalarocio.es\\\/fr\\\/la-zambra-del-sacromonte\\\/\",\"url\":\"https:\\\/\\\/cuevalarocio.es\\\/fr\\\/la-zambra-del-sacromonte\\\/\",\"name\":\"La Zambra del Sacromonte y la boda gitana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cuevalarocio.es\\\/fr\\\/#website\"},\"datePublished\":\"2020-04-15T09:59:41+00:00\",\"dateModified\":\"2026-06-23T17:04:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cuevalarocio.es\\\/fr\\\/#\\\/schema\\\/person\\\/f3c08095e0eef4f5a76f7cdcf76ee226\"},\"description\":\"La zambra es un baile t\u00edpico de los gitanos del Sacromonte y tiene una presencia muy clara en las bodas gitanas del Sacromonte granadino.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cuevalarocio.es\\\/fr\\\/la-zambra-del-sacromonte\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cuevalarocio.es\\\/fr\\\/la-zambra-del-sacromonte\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cuevalarocio.es\\\/fr\\\/la-zambra-del-sacromonte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cuevalarocio.es\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Zambra del Sacromonte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cuevalarocio.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/cuevalarocio.es\\\/fr\\\/\",\"name\":\"Cueva de La Roc\u00edo\",\"description\":\"Flamenco tablao \u00e0 Grenade et restaurant avec d\u00eener spectacle de flamenco \u00e0 Grenade\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cuevalarocio.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cuevalarocio.es\\\/fr\\\/#\\\/schema\\\/person\\\/f3c08095e0eef4f5a76f7cdcf76ee226\",\"name\":\"Adriana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79258bc864b6cdc0ffd4bec8bc6c806c8d564c2b86ce87a32cf2091ac77befbc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79258bc864b6cdc0ffd4bec8bc6c806c8d564c2b86ce87a32cf2091ac77befbc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79258bc864b6cdc0ffd4bec8bc6c806c8d564c2b86ce87a32cf2091ac77befbc?s=96&d=mm&r=g\",\"caption\":\"Adriana\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Zambra del Sacromonte y la boda gitana","description":"La zambra es un baile t\u00edpico de los gitanos del Sacromonte y tiene una presencia muy clara en las bodas gitanas del Sacromonte granadino.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cuevalarocio.es\/fr\/la-zambra-del-sacromonte\/","og_locale":"fr_FR","og_type":"article","og_title":"La Zambra del Sacromonte y la boda gitana","og_description":"La zambra es un baile t\u00edpico de los gitanos del Sacromonte y tiene una presencia muy clara en las bodas gitanas del Sacromonte granadino.","og_url":"https:\/\/cuevalarocio.es\/fr\/la-zambra-del-sacromonte\/","og_site_name":"Cueva de La Roc\u00edo","article_publisher":"https:\/\/www.facebook.com\/cuevalarocio","article_published_time":"2020-04-15T09:59:41+00:00","article_modified_time":"2026-06-23T17:04:50+00:00","og_image":[{"url":"https:\/\/cuevalarocio.es\/wp-content\/uploads\/2013\/09\/flamenco_1080x450.jpg","type":"","width":"","height":""}],"author":"Adriana","twitter_card":"summary_large_image","twitter_creator":"@cuevalarocio","twitter_site":"@cuevalarocio","twitter_misc":{"\u00c9crit par":"Adriana","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cuevalarocio.es\/fr\/la-zambra-del-sacromonte\/#article","isPartOf":{"@id":"https:\/\/cuevalarocio.es\/fr\/la-zambra-del-sacromonte\/"},"author":{"name":"Adriana","@id":"https:\/\/cuevalarocio.es\/fr\/#\/schema\/person\/f3c08095e0eef4f5a76f7cdcf76ee226"},"headline":"La Zambra del Sacromonte","datePublished":"2020-04-15T09:59:41+00:00","dateModified":"2026-06-23T17:04:50+00:00","mainEntityOfPage":{"@id":"https:\/\/cuevalarocio.es\/fr\/la-zambra-del-sacromonte\/"},"wordCount":1066,"articleSection":["espect\u00e1culos"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cuevalarocio.es\/fr\/la-zambra-del-sacromonte\/","url":"https:\/\/cuevalarocio.es\/fr\/la-zambra-del-sacromonte\/","name":"La Zambra del Sacromonte y la boda gitana","isPartOf":{"@id":"https:\/\/cuevalarocio.es\/fr\/#website"},"datePublished":"2020-04-15T09:59:41+00:00","dateModified":"2026-06-23T17:04:50+00:00","author":{"@id":"https:\/\/cuevalarocio.es\/fr\/#\/schema\/person\/f3c08095e0eef4f5a76f7cdcf76ee226"},"description":"La zambra es un baile t\u00edpico de los gitanos del Sacromonte y tiene una presencia muy clara en las bodas gitanas del Sacromonte granadino.","breadcrumb":{"@id":"https:\/\/cuevalarocio.es\/fr\/la-zambra-del-sacromonte\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cuevalarocio.es\/fr\/la-zambra-del-sacromonte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cuevalarocio.es\/fr\/la-zambra-del-sacromonte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cuevalarocio.es\/fr\/"},{"@type":"ListItem","position":2,"name":"La Zambra del Sacromonte"}]},{"@type":"WebSite","@id":"https:\/\/cuevalarocio.es\/fr\/#website","url":"https:\/\/cuevalarocio.es\/fr\/","name":"Cueva de La Roc\u00edo","description":"Flamenco tablao \u00e0 Grenade et restaurant avec d\u00eener spectacle de flamenco \u00e0 Grenade","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cuevalarocio.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/cuevalarocio.es\/fr\/#\/schema\/person\/f3c08095e0eef4f5a76f7cdcf76ee226","name":"Adriana","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/79258bc864b6cdc0ffd4bec8bc6c806c8d564c2b86ce87a32cf2091ac77befbc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/79258bc864b6cdc0ffd4bec8bc6c806c8d564c2b86ce87a32cf2091ac77befbc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/79258bc864b6cdc0ffd4bec8bc6c806c8d564c2b86ce87a32cf2091ac77befbc?s=96&d=mm&r=g","caption":"Adriana"}}]}},"_links":{"self":[{"href":"https:\/\/cuevalarocio.es\/fr\/wp-json\/wp\/v2\/posts\/5124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cuevalarocio.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cuevalarocio.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cuevalarocio.es\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/cuevalarocio.es\/fr\/wp-json\/wp\/v2\/comments?post=5124"}],"version-history":[{"count":26,"href":"https:\/\/cuevalarocio.es\/fr\/wp-json\/wp\/v2\/posts\/5124\/revisions"}],"predecessor-version":[{"id":5179,"href":"https:\/\/cuevalarocio.es\/fr\/wp-json\/wp\/v2\/posts\/5124\/revisions\/5179"}],"wp:attachment":[{"href":"https:\/\/cuevalarocio.es\/fr\/wp-json\/wp\/v2\/media?parent=5124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cuevalarocio.es\/fr\/wp-json\/wp\/v2\/categories?post=5124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cuevalarocio.es\/fr\/wp-json\/wp\/v2\/tags?post=5124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}